{"id":1409,"date":"2012-09-24T14:18:48","date_gmt":"2012-09-24T19:18:48","guid":{"rendered":"http:\/\/metalecabeza.org\/?p=1409"},"modified":"2012-09-24T14:18:48","modified_gmt":"2012-09-24T19:18:48","slug":"estrategias-online-al-servicio-de-las-campanas-politicas","status":"publish","type":"post","link":"https:\/\/moralescom.com\/site\/estrategias-online-al-servicio-de-las-campanas-politicas\/","title":{"rendered":"Estrategias online al servicio de las campa\u00f1as pol\u00edticas"},"content":{"rendered":"<p>Por: Dannisol A.B.<\/p>\n<p><a href=\"http:\/\/metalecabeza.org\/2012\/09\/24\/estrategias-online-al-servicio-de-las-campanas-politicas\/estrategiasonlinealserviciodelascampanaspoliticas-metalecabeza-moralescom\/\" rel=\"attachment wp-att-1729\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-1729\" alt=\"EstrategiasOnlineAlServiciodelasCampa\u00f1asPol\u00edticas-Metalecabeza-moralescom\" src=\"https:\/\/i0.wp.com\/metalecabeza.moralescom.com\/wp-content\/uploads\/2012\/09\/EstrategiasOnlineAlServiciodelasCampa%C3%B1asPol%C3%ADticas-Metalecabeza-moralescom.jpg?resize=340%2C270\" width=\"340\" height=\"270\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Las campa\u00f1as pol\u00edticas son claves para la consecuci\u00f3n del poder, sobre todo ahora que nos hallamos m\u00e1s all\u00e1 de la tendencia de la continuidad de los actuales jefes de Estado, la prolongaci\u00f3n en el cargo es m\u00e1s una cuesti\u00f3n de estrategias que una simple moda pol\u00edtica.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\"><strong>La ola de reelecciones ha impulsado el desarrollo creativo de estrategias, atr\u00e1s se est\u00e1n\u00a0 quedando los extensos discursos, las camisetas contramarcadas y otras pr\u00e1cticas poco ortodoxas.<\/strong><\/p>\n<p style=\"text-align: justify;\">Ahora l<strong>as contiendas electorales trascienden del mundo real al mundo virtua<\/strong>l, disput\u00e1ndose la credibilidad y el apoyo de los internautas no solo de su pa\u00eds sino del mundo, pues el internet ha derribado las barreras del tiempo y la distancia permitiendo el acceso a todos.<\/p>\n<p style=\"text-align: justify;\">Prueba de esto fue la pasada campa\u00f1a electoral del Presidente Obama quien centro sus esfuerzos en la realizaci\u00f3n de una estrategia combinada entre el mundo digital y el mundo real, basado en las estrategias del marketing y el uso de las redes sociales.<\/p>\n<p style=\"text-align: justify;\">El candidato construy\u00f3 una comunidad a su alrededor, se acerc\u00f3 a sus potenciales votantes y les demostr\u00f3 que estaba a su alcance y a su disposici\u00f3n, con mensajes personalizados, directos y asertivos en tiempo real; <strong>los asesores de Obama consiguieron que el favoritismo y la simpat\u00eda despertadas a trav\u00e9s de la web se materializar\u00e1, invitando a la gente a votar, a ser parte del cambio y la soluci\u00f3n.<\/strong><\/p>\n<p style=\"text-align: justify;\">Obama gan\u00f3 en el mundo virtual y tambi\u00e9n en la realidad y hoy, a pocos meses de finalizar su mandato y con la posibilidad de ser reelegido, sigue llevando la delantera en la preferencia de los votantes, aunque no con mucha ventaja. Pues a diferencia de las elecciones pasadas, al presente ya es el Presidente y debe lidiar con la mala publicidad que se genera alrededor de su gobernabilidad.<\/p>\n<p style=\"text-align: justify;\">\u00a0Sin embargo, no ha bajado la guardia; en esencia su estrategia es la misma, <strong>ha intensificado sus relaciones con la comunidad inmigrante y latina<\/strong>, adem\u00e1s <strong>ha dado la oportunidad a sus seguidores en sus distintas intervenciones p\u00fablicas de opinar y ser escuchados<\/strong> public\u00e1ndoles en su <a href=\"http:\/\/www.barackobama.com\/es\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>blog<\/strong><\/span><\/a> de campa\u00f1a.<\/p>\n<p style=\"text-align: justify;\"><strong>Las redes sociales se convirtieron en una herramienta creativa para acercarse a los votantes<\/strong> y posibilitaron la forma de revertir la creencia que las personas, usuarios de la web, han tenido sobre las \u201cdeidades\u201d de algunos candidatos, mostrando que ellos lejos de sus aspiraciones pol\u00edticas tambi\u00e9n son personas como ellos, que sue\u00f1an y consumen lo mismo que sus votantes.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s <strong>la publicidad que se genera a trav\u00e9s de la interacci\u00f3n de las redes sociales tiene un costo mucho menor<\/strong>, comparado con la publicidad tradicional y las propagandas acostumbradas para la elaboraci\u00f3n de Campa\u00f1as Pol\u00edticas, que evidentemente carecen de creatividad.<\/p>\n<p style=\"text-align: justify;\">Cabe decir, que el equipo del presidente Obama ha sido pionero en este tipo de estrategias publicitarias online y aunque algunos pol\u00edticos han tratado de imitarlos, no han tenido el mismo \u00e9xito.<\/p>\n<p style=\"text-align: justify;\">Despu\u00e9s del 6 de noviembre sabremos con exactitud hacia donde se encaminar\u00e1n las campa\u00f1as pol\u00edticas, porque <strong>si el Presidente Obama es reelegido\u00a0 ser\u00e1 un precedente exitoso en la historia de la comunicaci\u00f3n pol\u00edtica.<\/strong><\/p>\n<p style=\"text-align: justify;\">Ahora, <strong>\u00bfPor qu\u00e9 en Colombia este tipo de estrategias pol\u00edticas online no han tenido \u00e9xito?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Si usted lo sabe, cu\u00e9ntenos.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Dannisol A.B. Las campa\u00f1as pol\u00edticas son claves para la consecuci\u00f3n del poder, sobre todo ahora que nos hallamos m\u00e1s all\u00e1 de la tendencia de la continuidad de los actuales jefes de Estado, la prolongaci\u00f3n en el cargo es m\u00e1s una cuesti\u00f3n de estrategias que una simple moda pol\u00edtica.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[88,89,92],"tags":[258,259,109,106,260,261,143,186,262,97,263,264],"class_list":["post-1409","post","type-post","status-publish","format-standard","hentry","category-comunicacion-perceptual-2","category-comunicacion-inteligente","category-cultumidor","tag-barack-obama","tag-campanas-politicas","tag-colombia","tag-comunicacion-perceptual","tag-comunicacion-politica","tag-creatividad-online","tag-cultumidor-2","tag-eeuu","tag-estrategias-publicitarias","tag-moralescom","tag-politica-2-0","tag-redes-sociales"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/1409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/comments?post=1409"}],"version-history":[{"count":0,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/1409\/revisions"}],"wp:attachment":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/media?parent=1409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/categories?post=1409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/tags?post=1409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}