{"id":1932,"date":"2013-05-17T11:02:29","date_gmt":"2013-05-17T16:02:29","guid":{"rendered":"http:\/\/metalecabeza.org\/?p=1932"},"modified":"2013-05-17T11:02:29","modified_gmt":"2013-05-17T16:02:29","slug":"gamification-sera-la-formula-perfecta-para-aprender","status":"publish","type":"post","link":"https:\/\/moralescom.com\/site\/gamification-sera-la-formula-perfecta-para-aprender\/","title":{"rendered":"\u00bfGamification ser\u00e1 la f\u00f3rmula perfecta para aprender?"},"content":{"rendered":"<p style=\"text-align: right;\" align=\"JUSTIFY\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-1934\" style=\"border: 7px solid white; margin: 7px;\" alt=\"Gamificacion-una-formula-para-aprender-Metalecabeza-Moralescom-Cultumidor-jpg\" src=\"https:\/\/i0.wp.com\/metalecabeza.moralescom.com\/wp-content\/uploads\/2013\/05\/Gamificacion-una-formula-para-aprender-Metalecabeza-Moralescom-Cultumidor-jpg.jpg?resize=340%2C270\" width=\"340\" height=\"270\" \/>Escribe: Dannisol A.B.<\/p>\n<p style=\"text-align: justify;\" align=\"JUSTIFY\">El Gamification es una apuesta a la imaginaci\u00f3n y la creatividad.<\/p>\n<p style=\"text-align: justify;\" align=\"JUSTIFY\">El t\u00e9rmino no es de ahora, naci\u00f3 a mediados de los 80 y consiste en el desarrollo de actividades l\u00fadicas en entornos \u201cdiferentes\u201d, donde antes no se pensaba que jugar o divertirse era posible o apropiado.<\/p>\n<p style=\"text-align: justify;\" align=\"JUSTIFY\"><!--more--><\/p>\n<p style=\"text-align: justify;\" align=\"JUSTIFY\">Su implementaci\u00f3n abri\u00f3 un \u201c<strong>mundo de posibilidades<\/strong>\u201d, en la medida en que se ha aplicado en diferentes aspectos de la vida personal, laboral y social, por ejemplo, en procesos de inducci\u00f3n empresarial o educativos, actividades del marketing, recursos humanos y productividad.<\/p>\n<p style=\"text-align: justify;\" align=\"JUSTIFY\">Ciertamente, su pr\u00e1ctica est\u00e1 dotada de componentes multidisciplinarios como la ciencia, la tecnolog\u00eda, la psicolog\u00eda y la educaci\u00f3n, que sin duda, <strong>fomentan habilidades mentales, motrices y hasta sociales entre quienes participan de la misma<\/strong>. En este sentido, el \u201cgamification\u201d se configura como una herramienta, t\u00e9cnica o medio novedoso capaz de lograr un alto impacto entre sus interlocutores.<\/p>\n<p style=\"text-align: justify;\" align=\"JUSTIFY\">Sin embargo, plantear una actividad de este tipo no es tan simple Dicha acci\u00f3n debe cumplir ciertas condiciones de creatividad, est\u00edmulo, recompensas y objetivos para servir a estrategias tanto educativas como publicitarias y empresariales.<\/p>\n<p style=\"text-align: justify;\" align=\"JUSTIFY\">El \u201c<a href=\"http:\/\/www.tendencias21.net\/innovacion\/Gamification-innovar-jugando-y-viceversa_a46.html\" target=\"_blank\" rel=\"noopener\">gamificati\u00f3n<\/a>\u201d no es algo de la modernidad. M\u00e1s all\u00e1 del boom, prima la importancia de su empleo y lo que este conlleva, ya que <strong>los \u201cjuegos\u201d pueden estimular cambios de conducta o comportamiento poco positivos para un desarrollo integral humano<\/strong>, por ejemplo en el caso de los v\u00eddeo juegos violentos, se presume que las personas hacen catarsis de sus frustraciones al jugar pero cuando un ni\u00f1o pasa demasiado tiempo expuesto a ellos, sus relaciones interpersonales tienden a ser bruscas. En el caso de los avatares, se estimula el desarrollo de una vida virtual paralela, donde se cree tener el control y es como se sue\u00f1a ser.<\/p>\n<p style=\"text-align: justify;\" align=\"JUSTIFY\">Ambos casos son miradas extremas, pero en la era de la informaci\u00f3n los extremos est\u00e1n al orden del d\u00eda. Sin el debido cuidado, <strong>los \u201cjugadores\u201d se convierten f\u00e1cilmente en \u201cciberadictos\u201d o personas sedentarias con las extremidades atrofiadas y las habilidades sociales cuerpo a cuerpo y voz a voz fracturadas<\/strong>; por ello los extremos siempre ser\u00e1n malos.<\/p>\n<p style=\"text-align: justify;\" align=\"JUSTIFY\"><strong>Si bien el gamification tiene sus riesgos, no puede negarse que es una oportunidad para la educaci\u00f3n, tambi\u00e9n para el marketing, la publicidad y la comunicaci\u00f3n. Como siempre lo malo no est\u00e1 en el concepto ni en el contexto sino en el uso, generalmente desmedido y poco proporcional que le da el hombre a todo lo que desarrolla.<\/strong><\/p>\n<p style=\"text-align: justify;\" align=\"JUSTIFY\">\u00bfCu\u00e1l es el mejor ejemplo de gamification que conoces?<\/p>\n<p style=\"text-align: justify;\" align=\"JUSTIFY\">Otros enlaces de\u00a0inter\u00e9s:<\/p>\n<ul>\n<li><a style=\"font-size: 13px; line-height: 19px;\" href=\"http:\/\/blogs.gestion.pe\/innovaciondisrupcion\/2013\/05\/gamification-como-complemento.html\" target=\"_blank\" rel=\"noopener\">Gamification como complemento<\/a><\/li>\n<li><a style=\"font-size: 13px; line-height: 19px;\" href=\"http:\/\/www.lanacion.com.ar\/1574575-gamification-jugar-para-vivir\" target=\"_blank\" rel=\"noopener\">\n<p style=\"text-align: justify;\" align=\"JUSTIFY\">Gamification: jugar para vivir<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Escribe: Dannisol A.B. El Gamification es una apuesta a la imaginaci\u00f3n y la creatividad. El t\u00e9rmino no es de ahora, naci\u00f3 a mediados de los 80 y consiste en el desarrollo de actividades l\u00fadicas en entornos \u201cdiferentes\u201d, donde antes no se pensaba que jugar o divertirse era posible o apropiado.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[89],"tags":[106,132,311,322,12,99],"class_list":["post-1932","post","type-post","status-publish","format-standard","hentry","category-comunicacion-inteligente","tag-comunicacion-perceptual","tag-creatividad","tag-educacion","tag-gamification","tag-marketing","tag-publicidad"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/1932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/comments?post=1932"}],"version-history":[{"count":0,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/1932\/revisions"}],"wp:attachment":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/media?parent=1932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/categories?post=1932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/tags?post=1932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}