{"id":2478,"date":"2014-03-18T10:10:03","date_gmt":"2014-03-18T15:10:03","guid":{"rendered":"http:\/\/metalecabeza.org\/?p=2478"},"modified":"2014-03-18T10:10:03","modified_gmt":"2014-03-18T15:10:03","slug":"la-mujer-sigue-siendo-un-instrumento-del-mensaje-publicitario","status":"publish","type":"post","link":"https:\/\/moralescom.com\/site\/la-mujer-sigue-siendo-un-instrumento-del-mensaje-publicitario\/","title":{"rendered":"La mujer sigue siendo un instrumento del mensaje publicitario"},"content":{"rendered":"<p style=\"text-align: right;\">Escribe: Alberto Morales<\/p>\n<p style=\"text-align: justify;\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-2480\" style=\"border: 7px solid white; margin: 7px;\" alt=\"La-mujer-sigue-siendo-un-instrumento-de-la-publicidad-MoralesCom-Metalecabeza\" src=\"https:\/\/i0.wp.com\/metalecabeza.org\/wp-content\/uploads\/2014\/03\/La-mujer-sigue-siendo-un-instrumento-de-la-publicidad-MoralesCom-Metalecabeza.jpg?resize=340%2C270\" width=\"340\" height=\"270\" \/>Desde cuando<strong> los publicistas<\/strong> descubrieron a Freud, ellos, tan literales siempre, se <strong>reafirmaron en la idea de que la mujer deber\u00eda ser su objeto en los mensajes<\/strong>.<\/p>\n<p style=\"text-align: justify;\">En los pechos vibrantes de las chicas modelos terminaba el alcance de la creatividad. Bastaba que la fotograf\u00eda de un mujer sensual acompa\u00f1ara el producto, cualquiera fuera, o que la c\u00e1mara hiciera un paneo por sus nalgas rebosantes, para que se so\u00f1ara con la efectividad.<!--more--><\/p>\n<p style=\"text-align: justify;\">Ahh, es una delicia observar las piezas y mensajes de las d\u00e9cadas del 60 y el 70 para descubrir, sin sorpresas, esa obsesi\u00f3n publicitaria con la silueta femenina, los ojos entornados, la mirada seductora.<\/p>\n<p style=\"text-align: justify;\">Ya entrados en el mundo de la segmentaci\u00f3n, <strong>la mujer, adem\u00e1s de ser instrumento y objeto de la publicidad, se convirti\u00f3 a su vez en grupo objetivo del mensaje, <\/strong>pero esto no represent\u00f3 un cambio significativo en la manera como la industria publicitaria segu\u00eda mir\u00e1ndola.<\/p>\n<p style=\"text-align: justify;\">Dados a simplificarlo todo, entonces la convirtieron en <strong>estereotipos:<\/strong> La mujer ejecutiva, la seductora, la que es ama de casa, la audaz. Y entonces <strong>los mensajes no s\u00f3lo exacerban esos estereotipos sino que entregan una figura de mujer ajustada a los sue\u00f1os de los hombres:<\/strong> Cualquiera que sea el rol que se le asigne en el mensaje, es siempre una mujer delgada, de piernas largas, domesticada, bella, bella, bella a la manera en la que los hombres las conciben bellas.<\/p>\n<p style=\"text-align: justify;\">Y cuando el mensaje evoluciona a una combinaci\u00f3n de \u201ctodas las formas de lucha\u201d, y el bien o el servicio o la marca deben ser referidos en vivo en los programas de TV por presentadoras de secciones, o se hacen activaciones en las calles, entonces ellas deben ser tambi\u00e9n ajustadas al estereotipo y ser siempre delgadas, de piernas largas, domesticadas, bellas, bellas,bellas, a la manera en que los hombres las conciben bellas.<\/p>\n<p style=\"text-align: justify;\"><strong>En este mes en el que se celebra el d\u00eda internacional de los Derechos de la Mujer, reflexiona uno que en la actividad publicitaria si que falta trecho por recorrer&#8230;<\/strong>.<\/p>\n<p style=\"text-align: justify;\">______________________<br \/>\nImagen de www.sxc.hu<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escribe: Alberto Morales Desde cuando los publicistas descubrieron a Freud, ellos, tan literales siempre, se reafirmaron en la idea de que la mujer deber\u00eda ser su objeto en los mensajes. En los pechos vibrantes de las chicas modelos terminaba el alcance de la creatividad. Bastaba que la fotograf\u00eda de un mujer sensual acompa\u00f1ara el producto, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[337,340],"tags":[132,367,368,369,99],"class_list":["post-2478","post","type-post","status-publish","format-standard","hentry","category-etica-2","category-publicidad-2","tag-creatividad","tag-mensaje","tag-mujer","tag-producto","tag-publicidad"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/2478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/comments?post=2478"}],"version-history":[{"count":0,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/2478\/revisions"}],"wp:attachment":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/media?parent=2478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/categories?post=2478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/tags?post=2478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}