{"id":321,"date":"2009-07-31T15:01:11","date_gmt":"2009-07-31T15:01:11","guid":{"rendered":"http:\/\/metalecabeza.wordpress.com\/?p=321"},"modified":"2009-07-31T15:01:11","modified_gmt":"2009-07-31T15:01:11","slug":"el-debate-a-nuestro-cliente-metrosalud-en-el-concejo-de-medellin","status":"publish","type":"post","link":"https:\/\/moralescom.com\/site\/el-debate-a-nuestro-cliente-metrosalud-en-el-concejo-de-medellin\/","title":{"rendered":"EL DEBATE A NUESTRO CLIENTE METROSALUD EN EL CONCEJO DE MEDELLIN."},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/metalecabeza.moralescom.com\/wp-content\/uploads\/2009\/07\/logotipo-metrosalud-convertido.jpg\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter size-medium wp-image-322\" title=\"LOGOTIPO METROSALUD [Convertido]\" src=\"https:\/\/i0.wp.com\/metalecabeza.moralescom.com\/wp-content\/uploads\/2009\/07\/logotipo-metrosalud-convertido.jpg?resize=300%2C163\" alt=\"LOGOTIPO METROSALUD [Convertido]\" width=\"300\" height=\"163\" \/><\/a><\/p>\n<p><em>Escribe: Alberto Morales<\/em><\/p>\n<p>La construcci\u00f3n de la nueva imagen de Metrosalud no es un hecho aislado. Trabajamos en esta tarea en plena consecuencia con los lineamientos del Plan de Desarrollo de esa entidad que, con el leit motiv de \u201cla Metrosalud del ma\u00f1ana\u201d, busca desencadenar una revoluci\u00f3n desde el punto de vista de la infraestructura de salud, de la sostenibilidad, de la tecnolog\u00eda, de la relaci\u00f3n con los usuarios, de la relaci\u00f3n con sus p\u00fablicos internos.<\/p>\n<p>Se expresa que la prestaci\u00f3n de los servicios de salud ser\u00e1 a su vez una herramienta de construcci\u00f3n de ciudadan\u00eda, en tanto se construir\u00e1 una cultura de honestidad, de transparencia,\u00a0 de honradez a toda prueba.<\/p>\n<p>Est\u00e1bamos a punto de iniciar la primera campa\u00f1a interna.<\/p>\n<p>Y entonces el Concejo de la ciudad cita a este debate para denunciar irregularidades en algunos contratos, para denunciar su desacuerdo con las modalidades de contrataci\u00f3n a trav\u00e9s de tercer\u00edas e incluso el mismo cambio de imagen.<\/p>\n<p>En lo fundamental, todas las irregularidades denunciadas fueron descubiertas por los procesos de auditor\u00eda que adelanta la actual administraci\u00f3n, pero de cara a la opini\u00f3n p\u00fablica lo que quedaba en el aire era que \u201chab\u00eda corrupci\u00f3n en Metrosalud\u201d.<\/p>\n<p>El informe del Gerente fue impecable, bien documentado, incontrovertible.<\/p>\n<p>El problema de los debates pol\u00edticos en este tipo de organismos es que no son concluyentes.<\/p>\n<p>Al final, los concejales se limitan a decir que hay aspectos que no comparten y punto.<\/p>\n<p>Este es el reto desde el punto de vista de las comunicaciones: Existiendo un \u201cmarco\u201d que tiende una duda sobre la instituci\u00f3n, trabajaremos en modificar ese marco y en demostrar que precisamente, inspirados en una pol\u00edtica de cero tolerancia a la corrupci\u00f3n, seguiremos desentra\u00f1ando casos para denunciar, tomando medidas dr\u00e1sticas y trabajando de manera incansable por la Metrosalud del ma\u00f1ana.<\/p>\n<p>Ah\u00ed vamos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escribe: Alberto Morales La construcci\u00f3n de la nueva imagen de Metrosalud no es un hecho aislado. Trabajamos en esta tarea en plena consecuencia con los lineamientos del Plan de Desarrollo de esa entidad que, con el leit motiv de \u201cla Metrosalud del ma\u00f1ana\u201d, busca desencadenar una revoluci\u00f3n desde el punto de vista de la infraestructura [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[88,89,92,93],"tags":[124,128,97],"class_list":["post-321","post","type-post","status-publish","format-standard","hentry","category-comunicacion-perceptual-2","category-comunicacion-inteligente","category-cultumidor","category-inteligencia-de-marca","tag-alcaldia-de-medellin","tag-ciudadania","tag-moralescom"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/comments?post=321"}],"version-history":[{"count":0,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/321\/revisions"}],"wp:attachment":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/media?parent=321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/categories?post=321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/tags?post=321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}