{"id":3773,"date":"2015-10-19T22:20:39","date_gmt":"2015-10-19T22:20:39","guid":{"rendered":"http:\/\/moralescom.com\/sitio\/?p=3773"},"modified":"2015-10-19T22:20:39","modified_gmt":"2015-10-19T22:20:39","slug":"como-le-das-personalidad-a-una-marca","status":"publish","type":"post","link":"https:\/\/moralescom.com\/site\/como-le-das-personalidad-a-una-marca\/","title":{"rendered":"\u00bfC\u00f3mo le das personalidad a una marca?"},"content":{"rendered":"<p>[et_pb_section][et_pb_row][et_pb_column type=&#8221;4_4&#8243;][et_pb_text admin_label=&#8221;Texto&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: right;\">Escribe:@losinnad<\/p>\n<figure id=\"attachment_3780\" aria-describedby=\"caption-attachment-3780\" style=\"width: 292px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/i0.wp.com\/moralescom.com\/sitio\/wp-content\/uploads\/La-personalidad-de-una-marca-MoralesCom-Metalecabeza.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-3780\" src=\"https:\/\/i0.wp.com\/moralescom.com\/sitio\/wp-content\/uploads\/La-personalidad-de-una-marca-MoralesCom-Metalecabeza.jpg?resize=292%2C232\" alt=\"Las marcas al igual que las personas tiene personalidad\" width=\"292\" height=\"232\" \/><\/a><figcaption id=\"caption-attachment-3780\" class=\"wp-caption-text\">Las marcas al igual que las personas tienen personalidad<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Las cualidades de una marca son tan importantes como las cualidades de un producto, su calidad y su nombre, son aspectos determinantes para diferenciarse en el mercado y calar en las preferencias del \u201ccultumidor\u201d.<\/p>\n<p style=\"text-align: justify;\">Si una marca posee valores que capturan la atenci\u00f3n de las personas y generan empat\u00eda, ser\u00e1 percibida con caracter\u00edsticas tan propias como las de cualquier ser humano, de modo que constituir\u00e1 toda la estructura de una personalidad, d\u00e1ndole vida a la marca y dot\u00e1ndola de lo que con \u201c<a href=\"http:\/\/moralescom.com\/sitio\/inteligencia-de-marca\/\" target=\"_blank\" rel=\"noopener\">Inteligencia de Marca<\/a>\u201d llamamos \u201cpersonalidad p\u00fablica\u201d.<\/p>\n<p style=\"text-align: justify;\">Construir la personalidad p\u00fablica de una marca no es una tarea f\u00e1cil, no es tan simple como decir que sus valores son la transparencia o la amabilidad, ni mucho menos comienza argumentando la calidad del producto, la misi\u00f3n o visi\u00f3n de la empresa. Esta se construye con el tiempo, poco a poco, a trav\u00e9s de la percepci\u00f3n de los cultumidores y su p\u00fablico objetivo.<\/p>\n<p style=\"text-align: justify;\">Lo que las personas perciben es determinante para establecer los aspectos diferenciables de la marca y los ejes estrat\u00e9gicos que se deben desarrollar para proyectarla y mantener una identidad af\u00edn a su percepci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Si no sabe cu\u00e1l es la personalidad de su marca comience por comparar lo que quiere que las personas piensen de ella y lo que ellos realmente creen, tenga presente algunos interrogantes: El porqu\u00e9 la consumen, qu\u00e9 les atrae de ella y qu\u00e9 le cambiar\u00edan si tuvieran la oportunidad, c\u00f3mo llegaron a ella, qu\u00e9 pensaban antes de conocerla y qu\u00e9 cambi\u00f3 despu\u00e9s. Sin duda responderse lo anterior, le dar\u00e1 una idea de c\u00f3mo es percibido su producto, qu\u00e9 tan cerca o lejos est\u00e1 de lo que quer\u00eda mostrar y cu\u00e1les pueden ser sus directrices estrat\u00e9gicas para consolidar el desarrollo de su marca.<\/p>\n<p style=\"text-align: justify;\">Asimismo tendr\u00e1 una evidencia notable del desempe\u00f1o de la marca y su crecimiento comercial frente a sus competidores, estar\u00e1 en capacidad de usar e implementar otros <a href=\"http:\/\/marketingunea.com\/archivos\/1455\" target=\"_blank\" rel=\"noopener\">m\u00e9todos y modelos<\/a> que le proporcionar\u00e1n la informaci\u00f3n necesaria y suficiente para ser una empresa innovadora \u00a0en el mercado, y tendr\u00e1 la posibilidad de vencer las barreras del tiempo con un stock de cultumidores fieles.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las cualidades de una marca son tan importantes como las cualidades de un producto, su calidad y su nombre, son aspectos determinantes para diferenciarse en el mercado y calar en las preferencias del \u201ccultumidor\u201d.<\/p>\n","protected":false},"author":4,"featured_media":3779,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[93],"tags":[252,94,230,395],"class_list":["post-3773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inteligencia-de-marca","tag-estrategia","tag-marca","tag-mercado","tag-personalidad-publica"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/3773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/comments?post=3773"}],"version-history":[{"count":0,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/3773\/revisions"}],"wp:attachment":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/media?parent=3773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/categories?post=3773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/tags?post=3773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}