{"id":4006,"date":"2016-04-07T17:29:23","date_gmt":"2016-04-07T17:29:23","guid":{"rendered":"http:\/\/moralescom.com\/sitio\/?p=4006"},"modified":"2016-04-07T17:29:23","modified_gmt":"2016-04-07T17:29:23","slug":"la-etica-la-publicidad","status":"publish","type":"post","link":"https:\/\/moralescom.com\/site\/la-etica-la-publicidad\/","title":{"rendered":"La \u00e9tica en la publicidad"},"content":{"rendered":"<p>[et_pb_section admin_label=&#8221;section&#8221;][et_pb_row admin_label=&#8221;row&#8221;][et_pb_column type=&#8221;4_4&#8243;][et_pb_text admin_label=&#8221;Texto&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La publicidad no puede seguir concibi\u00e9ndose como una t\u00e9cnica orientada a \u00a0la manipulaci\u00f3n. Tal visi\u00f3n, no solo atenta contra la \u00e9tica, sino que desconoce la formidable evoluci\u00f3n de los p\u00fablicos contempor\u00e1neos. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Y es que considerar las teor\u00edas aspiracionales y sus juegos psicol\u00f3gicos, como el \u00fanico recurso para crear mensajes que motiven la compra, como si las personas fuesen m\u00e1quinas reprogramables que no piensan, que funcionan seg\u00fan las bases del est\u00edmulo &#8211; respuesta, \u00a0es una idea muy pobre del desarrollo humano.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Los \u201cexpertos\u201d que asumen la posibilidad de manipular a su p\u00fablico de esta forma desconocen la \u00e9tica y la transparencia en su trabajo, asumen el \u201c<a href=\"http:\/\/moralescom.com\/sitio\/inteligencia-de-marca\/\" target=\"_blank\" rel=\"noopener\">target<\/a>\u201d al que se dirigen como un reba\u00f1o de personas que solo hacen lo que se les dice o una masa que simplemente se amolda al objetivo que el publicista de turno plantea.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Incluso, cuando se habla de la teor\u00eda aspiracional en la publicidad encontramos anuncios como estos<\/span><span style=\"font-weight: 400;\">, \u201c<\/span><i><span style=\"font-weight: 400;\">Para que ser bueno si puedes ser el mejor\u201d de <\/span><\/i><span style=\"font-weight: 400;\">Mercedes Benz, \u00a0\u201c\u00bf<\/span><i><span style=\"font-weight: 400;\">Necesitas un cambio<\/span><\/i><span style=\"font-weight: 400;\">? <\/span><i><span style=\"font-weight: 400;\">Qu\u00e9 tal Nueve<\/span><\/i><span style=\"font-weight: 400;\">\u201d Jeep Cherokee, \u201c<\/span><i><span style=\"font-weight: 400;\">La vida se trata de momentos. No los esperes, cr\u00e9alos&#8230; Nueva gran <\/span><\/i><span style=\"font-weight: 400;\">Sedona SUV<\/span><i><span style=\"font-weight: 400;\">. Crea tu propia historia\u201d o \u201c La teletransportaci\u00f3n existe\u201d <\/span><\/i><span style=\"font-weight: 400;\">de Golft GTI, por mencionar algunos en la categor\u00eda de autom\u00f3viles.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;Fila&#8221;][et_pb_column type=&#8221;1_2&#8243;][et_pb_image admin_label=&#8221;Imagen&#8221; src=&#8221;http:\/\/moralescom.com\/sitio\/wp-content\/uploads\/periodico-abc-publicidad-mercedes-benz-01.jpg&#8221; show_in_lightbox=&#8221;off&#8221; url_new_window=&#8221;off&#8221; use_overlay=&#8221;off&#8221; animation=&#8221;left&#8221; sticky=&#8221;off&#8221; align=&#8221;left&#8221; force_fullwidth=&#8221;off&#8221; always_center_on_mobile=&#8221;on&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;] [\/et_pb_image][et_pb_image admin_label=&#8221;Imagen&#8221; src=&#8221;http:\/\/moralescom.com\/sitio\/wp-content\/uploads\/1BBDOMercedesSLlow.jpg&#8221; show_in_lightbox=&#8221;off&#8221; url_new_window=&#8221;off&#8221; use_overlay=&#8221;off&#8221; animation=&#8221;left&#8221; sticky=&#8221;off&#8221; align=&#8221;left&#8221; force_fullwidth=&#8221;off&#8221; always_center_on_mobile=&#8221;on&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;] [\/et_pb_image][et_pb_text admin_label=&#8221;Texto&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<h6>Im\u00e1genes:<br \/>\nMercedes Benz Dream Factoryde VVL\/BBDO Brussels, Belgium (<a href=\"http:\/\/creactivablog.blogspot.com.co\/2008\/04\/mercedes-benz-dream-factory.html\" target=\"_blank\" rel=\"noopener\">Blog creativa<\/a>)<br \/>\n<span style=\"font-weight: 400;\">Mercedes Benz Periodico ABC publicidad impresa (<a href=\"http:\/\/argentum47.com\/?portfolio=diario-periodico-abc-publicidad-impresa-prensa-motor-coches-mercedes-benz-class-clase-a\" target=\"_blank\" rel=\"noopener\">argentum47<\/a>)<\/span><br \/>\nFord Anglia &#8211; Abril 1958 (<a href=\"http:\/\/www.mimecanicapopular.com\/verautos.php?n=173\" target=\"_blank\" rel=\"noopener\">Revista Mec\u00e1nica Popular<\/a>)<\/h6>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243;][et_pb_image admin_label=&#8221;Imagen&#8221; src=&#8221;http:\/\/moralescom.com\/sitio\/wp-content\/uploads\/ford_anglia_abr58.jpg&#8221; show_in_lightbox=&#8221;off&#8221; url_new_window=&#8221;off&#8221; use_overlay=&#8221;off&#8221; animation=&#8221;left&#8221; sticky=&#8221;off&#8221; align=&#8221;left&#8221; force_fullwidth=&#8221;off&#8221; always_center_on_mobile=&#8221;on&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;] [\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;Fila&#8221;][et_pb_column type=&#8221;4_4&#8243;][et_pb_text admin_label=&#8221;Texto&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Hoy este tipo de anuncios no tiene tanto impacto como antes, porque el \u201cp\u00fablico objetivo\u201d es un nicho m\u00e1s peque\u00f1o y selectivo, y en la b\u00fasqueda de nuevos clientes se encuentran con personas, pensadores y cr\u00edticos &#8211; cultumidores- m\u00e1s consciente, con mayores opciones, que desean la autorrealizaci\u00f3n y la comodidad pero sin enga\u00f1arse, lo que poco a poco ha hecho que el discurso publicitario se agote ante la falta de inteligencia e investigaci\u00f3n del cliente.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La publicidad contempor\u00e1nea ser\u00e1 tanto m\u00e1s eficiente e impactante, en la medida en la que sea capaz de mirar a los p\u00fablicos objetivos como <\/span><b><a href=\"http:\/\/moralescom.com\/sitio\/teoria-del-cultumidor\/\" target=\"_blank\" rel=\"noopener\">seres humanos<\/a> <\/b><span style=\"font-weight: 400;\">que viven sus propias historias.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u00c9tica, respeto y humanismo\u2026 \u00bfes mucho pedir?<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La publicidad no puede seguir concibi\u00e9ndose como una t\u00e9cnica orientada a  la manipulaci\u00f3n. Tal visi\u00f3n, no solo atenta contra la \u00e9tica, sino que desconoce la formidable evoluci\u00f3n de los p\u00fablicos contempor\u00e1neos<\/p>\n","protected":false},"author":4,"featured_media":4015,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[88,340],"tags":[383,371,129,99,105],"class_list":["post-4006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacion-perceptual-2","category-publicidad-2","tag-cliente","tag-cultumidores","tag-etica","tag-publicidad","tag-target"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/4006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/comments?post=4006"}],"version-history":[{"count":0,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/4006\/revisions"}],"wp:attachment":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/media?parent=4006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/categories?post=4006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/tags?post=4006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}