{"id":4275,"date":"2018-04-02T14:20:39","date_gmt":"2018-04-02T14:20:39","guid":{"rendered":"http:\/\/moralescom.com\/sitio\/?p=4275"},"modified":"2018-04-02T14:20:39","modified_gmt":"2018-04-02T14:20:39","slug":"la-danza-los-estupidos","status":"publish","type":"post","link":"https:\/\/moralescom.com\/site\/la-danza-los-estupidos\/","title":{"rendered":"La danza de los est\u00fapidos"},"content":{"rendered":"<p>Escribe: Alberto Morales<br \/>\nEl c\u00e9lebre y tal vez \u00faltimo anarquista existente hoy, David Graeber, refiere un ejercicio popularizado en la preparatoria de los Estados Unidos: se pide a los estudiantes que describan c\u00f3mo ser\u00eda un d\u00eda de sus vidas si se hubiesen transformado (solo por ese d\u00eda) en alguien del sexo opuesto. Explica que los resultados son \u201casombrosamente uniformes\u201d. Las chicas tienden a escribir largos ensayos, muy detallados, que \u201cclaramente muestran que han pasado mucho tiempo pensando en el tema\u201d, mientras que, por lo general, m\u00e1s de la mitad de los chicos se niegan a escribir el ensayo completo y expresan que no tienen ni idea y que les molesta profundamente tener que pensar en ello.<br \/>\nLa an\u00e9cdota le permite a Graeber hacer una larga disquisici\u00f3n sobre el machismo y el desprecio que se tiene desde una posici\u00f3n de \u201cpoder\u201d a imaginar cualquier cosa, pero sirve tambi\u00e9n para aportar una reflexi\u00f3n sobre el inusitado crecimiento de la estupidez en el mundo contempor\u00e1neo.<\/p>\n<p>En t\u00e9rminos de diccionario, se refiere al est\u00fapido como aquel que tiene ausencia de sensatez, a quien le falta entendimiento, quien es notablemente torpe para comprender.<br \/>\nAquel que no piensa.<\/p>\n<p>Y entonces, a la manera de una pandemia, se ha impuesto la idea individualizada de que nada merece un an\u00e1lisis. \u00bfPara qu\u00e9? -piensa la gente, e incluso lo verbaliza- \u00bfqu\u00e9 objeto va a tener la m\u00e1s m\u00ednima reflexi\u00f3n si aqu\u00ed nunca pasa nada?<\/p>\n<h3>Las cosas se olvidan f\u00e1cilmente. Nos han vendido la idea de que los acontecimientos se suceden a una tal velocidad, que el inter\u00e9s cambia de un minuto a otro. El mundo pasa raudo frente a nuestros ojos y nosotros apenas lo notamos.<\/h3>\n<p>Alain Finkielkraut es un fil\u00f3sofo franc\u00e9s que ha dedicado tiempo a reflexionar sobre el tema.<\/p>\n<p>El origen de esta deplorable situaci\u00f3n, dice \u00e9l, se centra en lo que denomina el \u201caniquilamiento de la individualidad\u201d que, bajo la conspiraci\u00f3n de la aldea global, no solo arrasa con el aprendizaje de la duda, sino con la diversidad de las culturas, para concluir que ya no se puede aspirar a \u201cuna sociedad aut\u00e9ntica, en la que todos los individuos vivan c\u00f3modamente en su identidad cultural, sino a una sociedad polimorfa. Lo multicultural es entendido arbitrariamente como un mundo bien surtido, en el que lo que se aprecia no son las culturas como tales sino su versi\u00f3n edulcorada\u201d.<\/p>\n<p>Su descripci\u00f3n de las nuevas realidades es, adem\u00e1s de cierta, verdaderamente pat\u00e9tica: \u201cSiempre que lleve la firma de un gran dise\u00f1ador, un par de botas equivale a Shakespeare; una frase publicitaria eficaz equivale a un poema de Apollinaire o de Francis Ponge; un ritmo de Rock equivale a una melod\u00eda de Duke Ellington; un partido de f\u00fatbol equivale a un ballet de Pina Bausch, un gran modisto equivale a Manet\u2026\u201d<br \/>\nLo grave no es esto, pues la \u00e9tica, al igual que los placeres, empieza tambi\u00e9n a vivirse a la carta. El pensamiento deja entonces de ser un valor supremo y se vuelve tan facultativo como la loter\u00eda primitiva. Todo en el universo se convierte en opciones leg\u00edtimas\u00a0y desaparecen las obligaciones.<\/p>\n<p>Todo gira alrededor de la inmediatez de las pasiones m\u00e1s elementales.<\/p>\n<p>La tesis de Finkielfraut es que la cultura se ha disuelto en tanto se ha borrado la frontera entre la cultura y la diversi\u00f3n.<\/p>\n<p>Un efecto demoledor del triunfo de la estupidez, es que han desaparecido por lo tanto los lugares para acoger y para conferir sentido a la cultura en el sentido antiguo del t\u00e9rmino. La vida guiada por el intelecto ha perdido significaci\u00f3n.<\/p>\n<p>El universo light tiene la iniciativa. Todo es liviano, la vida es liviana, los medios son livianos, los h\u00e9roes son livianos, los influenciadores son livianos. Todos a una trabajando de manera sistem\u00e1tica para construir lo que Finkielkraut llama el \u201cdebilitamiento de la voluntad\u201d. As\u00ed, la ceguera hace met\u00e1stasis y quedamos en poder de la barbarie.<\/p>\n<p>El libro cierra con un axioma doloroso: \u201cLa vida guiada por el pensamiento cede suavemente su lugar al terrible y rid\u00edculo cara a cara del fan\u00e1tico y del zombie\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escribe: Alberto Morales El c\u00e9lebre y tal vez \u00faltimo anarquista existente hoy, David Graeber, refiere un ejercicio popularizado en la preparatoria de los Estados Unidos: se pide a los estudiantes que describan c\u00f3mo ser\u00eda un d\u00eda de sus vidas si se hubiesen transformado (solo por ese d\u00eda) en alguien del sexo opuesto. Explica que los [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4276,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[337,84],"tags":[408,114,409,143,149,410,411,412,413],"class_list":["post-4275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-etica-2","category-aberraciones-personales","tag-alain-finkielkraut","tag-comunicacion-estrategica","tag-comunicaron","tag-cultumidor-2","tag-cultura","tag-diversion","tag-inteligencia","tag-pensamiento","tag-universo-light"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/4275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/comments?post=4275"}],"version-history":[{"count":0,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/4275\/revisions"}],"wp:attachment":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/media?parent=4275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/categories?post=4275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/tags?post=4275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}