{"id":4297,"date":"2018-05-07T10:00:17","date_gmt":"2018-05-07T10:00:17","guid":{"rendered":"http:\/\/moralescom.com\/sitio\/?p=4297"},"modified":"2020-12-12T12:43:45","modified_gmt":"2020-12-12T12:43:45","slug":"in-nomini-patris","status":"publish","type":"post","link":"https:\/\/moralescom.com\/site\/in-nomini-patris\/","title":{"rendered":"IN NOMINI PATRIS"},"content":{"rendered":"<p>Escribe: Alberto Morales<br \/>\nEn 1976, Arthur Miller escribi\u00f3 una interesante reflexi\u00f3n sobre el fascismo para el primer n\u00famero de la revista mejicana Nueva Pol\u00edtica, destacando que <em>\u201clos reg\u00edmenes autocr\u00e1ticos, sin tomar en<\/em>&nbsp;<em>cuenta los intereses a que sirvan, son regresivos\u201d y solt\u00f3 una frase lapidaria: \u201cel fascismo es la<\/em>&nbsp;<i>nostalgia armada, ese anhelo por una unidad perdida en la que cada uno estaba en su sitio <\/i><strong style=\"font-style: italic;\">y<\/strong>&nbsp;<em><strong>grandes y desinteresados hombres guiaban a la sociedad\u2026<\/strong>\u201d<\/em><\/p>\n<p>El subrayado, que denomino \u201cla par\u00e1bola del padre estricto\u201d, es uno de los aspectos centrales del aprendizaje que podemos tener del actual debate electoral, porque toca virtualmente todos los componentes de las ideas que se agitan.<\/p>\n<p>Es cierto, hay sectores de la sociedad que sue\u00f1an con un padre que los salve y gu\u00ede. Su voto act\u00faa en consecuencia con esa aspiraci\u00f3n.<\/p>\n<p>Esa creencia no es gratuita. Se les ha sembrado de manera sistem\u00e1tica mediante la difusi\u00f3n de unas ideas construidas en el medioevo lejano y que se actualizan regularmente. George Lakoff las sistematiza as\u00ed:<br \/>\n. El mundo es y siempre ser\u00e1 peligroso, porque el mal se encuentra en \u00e9l.<br \/>\n. El mundo es muy competitivo. Siempre habr\u00e1 perdedores y ganadores.<br \/>\n. Hay un bien absoluto y un mal absoluto.<br \/>\n. Los ni\u00f1os nacen malos, solo quieren hacer lo que les gusta, pero lo que les gusta no es lo bueno.<\/p>\n<p>Un mundo as\u00ed de siniestro necesita un padre fuerte que logre:<br \/>\n. Proteger a la familia de ese mundo peligroso.<br \/>\n. Sostenerla en ese mundo dif\u00edcil.<br \/>\n. Ense\u00f1ar a todos la diferencia que existe entre el bien y el mal.<\/p>\n<p>La obediencia al padre es la virtud m\u00e1s importante y necesaria, pues ese padre es adem\u00e1s la autoridad moral. El castigo fuerte, severo, es lo \u00fanico que educa. El orden y la disciplina son la virtud para la construcci\u00f3n de la felicidad.<\/p>\n<p>Lo sintetizan todo con una definici\u00f3n c\u00e9lebre de Adam Smith a prop\u00f3sito de lo que significa ser una buena persona, una persona moral:<em> \u201calguien lo bastante disciplinado como para ser<\/em>&nbsp;<em>obediente, para aprender lo que es bueno, para hacer lo que est\u00e1 bien y no hacer lo que est\u00e1 mal\u201d<\/em><\/p>\n<p>Esta teor\u00eda, que acoge adem\u00e1s lo m\u00e1s recalcitrante del machismo, es la que inspira la l\u00f3gica de&nbsp;la mano firme, autoritaria, recia, implacable, que caracteriza al fascismo en todas sus versiones, en donde es necesario tener \u201cpermiso\u201d para los actos m\u00e1s cotidianos y la sociedad act\u00faa de manera restringida, ordenada, sometida, sin atreverse a pensar.<\/p>\n<p>Los textos de sicolog\u00eda infantil abundan en an\u00e1lisis sobre las consecuencias que tiene en el adulto el crecer bajo la direcci\u00f3n y control de un padre estricto:<\/p>\n<p><em>\u201cesos ni\u00f1os no ser\u00e1n capaces de aprender las habilidades necesarias para pensar y tomar<\/em>&nbsp;<em>decisiones de manera independiente, no sienten confianza ni seguridad en ellos mismos porque no se les ha dado la oportunidad de decidir ni de aprender de los errores. Carecen de autoestima<\/em>&nbsp;<em>y de confianza. Han aprendido que sus ideas o sus opiniones no tienen valor, solo valen las ideas<\/em>&nbsp;<em>y opiniones del padre\u201d.<\/em><\/p>\n<p>V\u00edctimas de esta visi\u00f3n nefasta, es com\u00fan identificar a estos ni\u00f1os no solo por la manera en que reaccionan en la defensa de su verdad (cuando se encuentran en el predicamento de la \u201cdeliberaci\u00f3n\u201d pol\u00edtica), sino por la deplorable respuesta que brindan cuando se les pregunta por qui\u00e9n van a votar:<em> \u201cPor el que diga el padre\u2026\u201d<\/em><\/p>\n<p>No suena desquiciada la propuesta del foco en la educaci\u00f3n, una educaci\u00f3n que ense\u00f1e a razonar, pues como bien lo expresa Savater: <em>\u201cla gracia de la raz\u00f3n es que sirve para, sin llegar a<\/em>&nbsp;<em>la violencia o el crimen, dirimir las cuestiones entre los seres humanos\u201d.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escribe: Alberto Morales En 1976, Arthur Miller escribi\u00f3 una interesante reflexi\u00f3n sobre el fascismo para el primer n\u00famero de la revista mejicana Nueva Pol\u00edtica, destacando que \u201clos reg\u00edmenes autocr\u00e1ticos, sin tomar en&nbsp;cuenta los intereses a que sirvan, son regresivos\u201d y solt\u00f3 una frase lapidaria: \u201cel fascismo es la&nbsp;nostalgia armada, ese anhelo por una unidad perdida [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4422,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[88,337,84],"tags":[423,311,424,425,426],"class_list":["post-4297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacion-perceptual-2","category-etica-2","category-aberraciones-personales","tag-creencias-ninos","tag-educacion","tag-padres-salvador","tag-sicologia-infantil","tag-votar"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/moralescom.com\/site\/wp-content\/uploads\/2020\/12\/father-son11.jpg?fit=2500%2C1674&ssl=1","_links":{"self":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/4297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/comments?post=4297"}],"version-history":[{"count":1,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/4297\/revisions"}],"predecessor-version":[{"id":4430,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/4297\/revisions\/4430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/media\/4422"}],"wp:attachment":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/media?parent=4297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/categories?post=4297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/tags?post=4297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}