{"id":4300,"date":"2018-05-14T10:34:49","date_gmt":"2018-05-14T10:34:49","guid":{"rendered":"http:\/\/moralescom.com\/sitio\/?p=4300"},"modified":"2020-12-12T12:43:31","modified_gmt":"2020-12-12T12:43:31","slug":"la-parabola-del-impune","status":"publish","type":"post","link":"https:\/\/moralescom.com\/site\/la-parabola-del-impune\/","title":{"rendered":"LA PAR\u00c1BOLA DEL IMPUNE"},"content":{"rendered":"<p><strong>Escribe Alberto Morales<\/strong><\/p>\n<p>Son muy raras las indignaciones de la gente. Son muy raras &#8211; digo &#8211; las cosas que a veces indignan y las que, debiendo indignar, no indignan. Es una especie de dicotom\u00eda \u00e9tica muy dif\u00edcil de digerir. Vea por ejemplo los casos de \u201custed no sabe qui\u00e9n soy yo\u201d.<\/p>\n<p>La gente se exacerba con ese personajillo insignificante que, presa de su condici\u00f3n de lagarto irredimible, atrapado en la mara\u00f1a de su apellido o v\u00edctima de la autovaloraci\u00f3n exagerada de su dinero o de su cargo, se dirige al resto de los seres humanos mir\u00e1ndonos por encima del hombro y, cuando eventualmente es atrapado en la infracci\u00f3n o se le exige que cumpla una norma, suelta con \u00ednfulas de superioridad la frasecita c\u00e9lebre para conminar a que tengamos cuidado porque \u201c\u00e9l es el que es\u201d.<\/p>\n<h3>Esa misma gente indignada es incapaz de expresarse, movilizarse, agitarse, frente a casos flagrantes de impunidad en los que los responsables, con la misma actitud prepotente del personajillo, se eximen de todo, mienten con descaro y, sin que les tiemble la voz, miran a los ojos y dicen \u201cyo no fui\u201d. Entonces escuchan y aplauden.<\/h3>\n<p>Para el impune la responsabilidad penal no existe, tampoco la responsabilidad civil, la administrativa o la disciplinaria. El impune escapa a toda investigaci\u00f3n, para el impune no hay<br \/>\ncondenas, no tiene que indemnizar a nadie. El impune camina por este mundo con la certeza absoluta de que el concepto de la justicia no se aplica a \u00e9l. Impunidad viene de \u201cimpunitas\u201d que significa falta de castigo.<\/p>\n<p>El impune es c\u00ednico en el sentido literal de la palabra: \u201cpractica de formas descarada, imp\u00fadica, deshonesta, algo que merece general desaprobaci\u00f3n\u201d.<\/p>\n<p>La historia de la impunidad en el mundo es larga y ancha. De ella han sido protagonistas empresarios y banqueros con sus cr\u00edmenes econ\u00f3micos execrables, dictadores, reyezuelos, militares, pol\u00edticos y reconocidos delincuentes. Mire usted menciones emblem\u00e1ticas:<\/p>\n<p>Los Zetas, Pinochet, los cr\u00edmenes del franquismo, por ejemplo.<\/p>\n<p>Un pa\u00eds como el nuestro parece ser la mata de la impunidad, precisamente porque se ha convertido en la mata de la corrupci\u00f3n. Existe entre corrupci\u00f3n e impunidad una relaci\u00f3n de vasos comunicantes.<\/p>\n<p>Es imposible encontrar casos m\u00e1s aberrantes:<br \/>\nQue exista un contubernio entre algunos Magistrados de las altas Cortes, por ejemplo, capaces de poner sus decisiones al servicio del mejor postor y que act\u00faen en gabela, a la manera de un cartel, para cuidarse las espaldas, es un exabrupto de proporciones colosales.<\/p>\n<p>As\u00ed mismo, los analistas honrados confluyen en describir el R\u00e9gimen de Contrataci\u00f3n de Obras P\u00fablicas en Colombia como un siniestro y enmara\u00f1ado artilugio de incisos dise\u00f1ados en beneficio de los contratistas corruptos, para que no les pase nada desde el punto de vista legal. Todos sus<br \/>\nactos dolosos se ejecutan sin violar la ley.<\/p>\n<p>Entonces surge la pregunta: \u00bfQu\u00e9 explica esta dicotom\u00eda, esta indignaci\u00f3n selectiva? Y aparece, luminoso, Harry G Frankfurt, profesor em\u00e9rito de la Universidad de Princeton quien se ha dedicado a reflexionar sobre el tema de \u201cla verdad\u201d<\/p>\n<p>Aprende uno acerca de los estragos que ha hecho esa construcci\u00f3n del \u201cescepticismo sobre la verdad\u201d que de manera sistem\u00e1tica se ha sembrado en la mente de nuestra gente desde las remotas \u00e9pocas de la conquista espa\u00f1ola. No nos gusta conocer las cosas como realmente son, le huimos al pensamiento, somos los campeones del eufemismo.<\/p>\n<p>El profesor Frankfurt plantea que esa \u201causencia del inter\u00e9s por la verdad\u201d es tierra abonada para el imperio de la charlataner\u00eda. El mundo en general y nuestro pa\u00eds en particular ha ca\u00eddo en manos de la charlataner\u00eda.<\/p>\n<p>Los vivos, poco serios, mentiroso, est\u00e1n en el poder, manejan la mayor\u00eda de los medios de comunicaci\u00f3n, orientan a la opini\u00f3n p\u00fablica. La charlataner\u00eda se ha convertido en un \u201cmodus vivendi\u201d y por ello la impunidad, al igual que la corrupci\u00f3n, fluyen y reinan.<\/p>\n<p>Dice el profesor Frankfurt: \u201cNadie en su sano juicio confiar\u00eda en un constructor o se someter\u00eda al cuidado de un m\u00e9dico a quienes la verdad los tenga sin cuidado\u201d.<\/p>\n<p>Pues parecer\u00eda que en este pa\u00eds nos tiene sin cuidado la verdad a la hora de elegir a nuestros gobernantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escribe Alberto Morales Son muy raras las indignaciones de la gente. Son muy raras &#8211; digo &#8211; las cosas que a veces indignan y las que, debiendo indignar, no indignan. Es una especie de dicotom\u00eda \u00e9tica muy dif\u00edcil de digerir. Vea por ejemplo los casos de \u201custed no sabe qui\u00e9n soy yo\u201d. La gente se [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4426,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[89,337,84],"tags":[109,427,428,129,358,429,430],"class_list":["post-4300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacion-inteligente","category-etica-2","category-aberraciones-personales","tag-colombia","tag-corruccino","tag-cortes","tag-etica","tag-indignacion","tag-indignazione","tag-verdad"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/moralescom.com\/site\/wp-content\/uploads\/2020\/12\/INDIGNADOS-NONOSVAMOS-SpanishRevolution-011.png?fit=977%2C596&ssl=1","_links":{"self":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/4300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/comments?post=4300"}],"version-history":[{"count":1,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/4300\/revisions"}],"predecessor-version":[{"id":4429,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/4300\/revisions\/4429"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/media\/4426"}],"wp:attachment":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/media?parent=4300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/categories?post=4300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/tags?post=4300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}