{"id":4393,"date":"2009-02-13T14:30:22","date_gmt":"2009-02-13T14:30:22","guid":{"rendered":"http:\/\/metalecabeza.wordpress.com\/?p=223"},"modified":"2009-02-13T14:30:22","modified_gmt":"2009-02-13T14:30:22","slug":"la-comunicacion-perceptual-como-vision-de-mercadeo-y-el-efecto-protesta-en-la-decision-de-compra","status":"publish","type":"post","link":"https:\/\/moralescom.com\/site\/la-comunicacion-perceptual-como-vision-de-mercadeo-y-el-efecto-protesta-en-la-decision-de-compra\/","title":{"rendered":"LA COMUNICACI\u00d3N PERCEPTUAL COMO VISI\u00d3N DE MERCADEO Y EL EFECTO \u201cPROTESTA\u201d EN LA DECISI\u00d3N DE COMPRA."},"content":{"rendered":"<p><!--StartFragment--><\/p>\n<p class=\"MsoNormal\"><em>Escribe: Alberto Morales<\/em><\/p>\n<p class=\"MsoNormal\">Es emocionante encontrar todos los d\u00edas referencias y argumentos que nos reafirman en la idea de que la <a href=\"http:\/\/metalecabeza.wordpress.com\/2008\/06\/11\/en-la-era-de-la-arquicultura-comunicacional-el-mensaje-apunta-a-las-creencias\/\">\u201cComunicaci\u00f3n Perceptual\u201d<\/a> es una visi\u00f3n revolucionaria al servicio de la Publicidad y el marketing.<\/p>\n<p class=\"MsoNormal\">-Ver reflexi\u00f3n completa-<\/p>\n<p class=\"MsoNormal\">El libro se llama \u201cModos de Pensar\u201d y la autora es Mary Douglas. Expresa que \u201ces err\u00f3neo considerar al consumidor como un ser incoherente y fragmentario,\u00a0 una persona dividida en sus prop\u00f3sitos y apenas responsable de sus decisiones, dominada de un lado por la reacci\u00f3n de los precios y, por el otro, por los vaivenes de la moda\u2026\u201d<!--more--><\/p>\n<p class=\"MsoNormal\">Hay publicistas y estrategas que ven al consumidor como un imb\u00e9cil chiquito, manipulable, indefenso.<\/p>\n<p class=\"MsoNormal\">Para Mary Douglas la protesta es el aspecto del consumo que revela al consumidor como una persona coherente y racional. \u201cLa protestas una postura cultural fundamental. En todo tiempo una cultura acusa a otras culturas\u2026 muchas conductas del consumo\u00a0 est\u00e1n continua y penetrantemente inspiradas por la hostilidad cultural\u201d.<\/p>\n<p class=\"MsoNormal\">\u201cLa elecci\u00f3n b\u00e1sica que\u00a0 tiene que hacer un individuo racional es una elecci\u00f3n sobre el tipo de sociedad en la que quiere vivir\u201d<\/p>\n<p class=\"MsoNormal\">Y esa es a nuestro juicio la quinta esencia de la \u201cComunicaci\u00f3n Perceptual\u201d.<\/p>\n<p class=\"MsoNormal\">Los alimentos que se consumen, la ropa que se usa, el cine que se ve, los libros que se leen, la m\u00fasica que se escucha, las vacaciones que se eligen y todo lo dem\u00e1s, son elecciones que corresponden a un sistema de creencias, a una relaci\u00f3n cultural entre el individuo y el tipo de sociedad con el que interact\u00faa.<\/p>\n<p class=\"MsoNormal\">Contrario a lo que se pueda pensar, los objetos no son neutrales. Son objetos y decisiones que no ser\u00edan tolerados en el tipo de sociedad que el individuo rechaza. Es por ello que en el acto de consumo es un acto de reafirmaci\u00f3n y un acto de protesta.<\/p>\n<p class=\"MsoNormal\">Nos gusta esta mirada, porque coincide con lo que pensamos del rol de la <a href=\"http:\/\/metalecabeza.wordpress.com\/2008\/06\/01\/manana-o-pasado-manana-todo-el-mundo-va-a-estar-hablando-de-arquicultura-en-el-mundo-del-marketing-y-las-publicidad\/\">publicidad y la importancia de la cultura en la decisi\u00f3n de marketing.<\/a><\/p>\n<p class=\"MsoNormal\">&nbsp;<\/p>\n<p><!--EndFragment--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escribe: Alberto Morales Es emocionante encontrar todos los d\u00edas referencias y argumentos que nos reafirman en la idea de que la \u201cComunicaci\u00f3n Perceptual\u201d es una visi\u00f3n revolucionaria al servicio de la Publicidad y el marketing. -Ver reflexi\u00f3n completa- El libro se llama \u201cModos de Pensar\u201d y la autora es Mary Douglas. Expresa que \u201ces err\u00f3neo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[88],"tags":[106,97,135],"class_list":["post-4393","post","type-post","status-publish","format-standard","hentry","category-comunicacion-perceptual-2","tag-comunicacion-perceptual","tag-moralescom","tag-publicidad-y-marketing"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/4393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/comments?post=4393"}],"version-history":[{"count":0,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/4393\/revisions"}],"wp:attachment":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/media?parent=4393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/categories?post=4393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/tags?post=4393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}