{"id":4398,"date":"2010-12-15T17:03:55","date_gmt":"2010-12-15T17:03:55","guid":{"rendered":"http:\/\/metalecabeza.wordpress.com\/?p=487"},"modified":"2010-12-15T17:03:55","modified_gmt":"2010-12-15T17:03:55","slug":"la-campana-amigos-de-bavaria","status":"publish","type":"post","link":"https:\/\/moralescom.com\/site\/la-campana-amigos-de-bavaria\/","title":{"rendered":"La campa\u00f1a &#8220;amigos&#8221; de Bavaria."},"content":{"rendered":"<p>Tengo que confesar que esta campa\u00f1a en la que existe la intenci\u00f3n institucional de generar empat\u00eda con la marca desde la argumentaci\u00f3n de la amistad, me genera sentimientos equ\u00edvocos.<\/p>\n<p>Estos dos hombres que son los \u00fanicos habitantes del pueblo y que desarrollan sus vidas en funci\u00f3n el uno del otro, me generan la impresi\u00f3n de ser una pareja estable que ha decidido vivir en su paraiso.<\/p>\n<p>Hay un t\u00e9rmino de rigurosa aplicaci\u00f3n en los mensajes publicitarios y que\u00a0es com\u00fan que olviden los &#8220;creativos&#8221;: verosimilitud. El mensaje\u00a0tiene que ser verosimil.<\/p>\n<p>Garc\u00eda Marquez\u00a0explicaba que tuvo\u00a0 muchas dificultades para que\u00a0Remedios la Bella en Cien A\u00f1os de Soledad, se elevara al cielo en cuerpo y alma. Por m\u00e1s que intentaba en la narraci\u00f3n, Remedios no se elevaba. La verosimilitud ingres\u00f3 a la historia cuando empez\u00f3 a agitarse un ventarr\u00f3n. Fue el viento el que elev\u00f3 las s\u00e1banas en el patio y tras ella elev\u00f3 a Remedios.<\/p>\n<p>Si no hay verosimilitud el mensaje no genera empat\u00eda.<\/p>\n<p>Tengo dudas en el sentido de que la campa\u00f1a de Bavaria est\u00e9 cumpliendo su objetivo&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bavaria, amigos, creatividad, Cien a\u00f1os de soledad, Remedios la bella, verosimilitud. <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[89],"tags":[],"class_list":["post-4398","post","type-post","status-publish","format-standard","hentry","category-comunicacion-inteligente"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/4398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/comments?post=4398"}],"version-history":[{"count":0,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/4398\/revisions"}],"wp:attachment":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/media?parent=4398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/categories?post=4398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/tags?post=4398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}