{"id":4405,"date":"2011-05-11T20:32:36","date_gmt":"2011-05-11T20:32:36","guid":{"rendered":"http:\/\/metalecabeza.wordpress.com\/?p=626"},"modified":"2011-05-11T20:32:36","modified_gmt":"2011-05-11T20:32:36","slug":"tres-razones-poderosas-que-obligan-a-que-la-publicidad-cambie","status":"publish","type":"post","link":"https:\/\/moralescom.com\/site\/tres-razones-poderosas-que-obligan-a-que-la-publicidad-cambie\/","title":{"rendered":"Tres razones poderosas que obligan a que la publicidad cambie."},"content":{"rendered":"<p lang=\"es-CO\"><span style=\"font-family:Arial, sans-serif;\">Son tres aspectos relevantes que definen el estado del mundo del mercadeo y de la comunicaci\u00f3n por objetivos hoy:<\/span><\/p>\n<p lang=\"es-CO\"><span style=\"font-family:Arial, sans-serif;\"><strong>1.- El primero es el que denomino \u201cescenario de guerra\u201d.<\/strong><\/span><\/p>\n<p lang=\"es-CO\"><span style=\"font-family:Arial, sans-serif;\">Y no se trata de darle una nueva denominaci\u00f3n a la \u201ceconom\u00eda de mercado\u201d y al concepto de la \u201clibre concurrencia\u201d.<\/span><\/p>\n<p lang=\"es-CO\"><span style=\"font-family:Arial, sans-serif;\">No se trata solamente de reivindicar la condici\u00f3n de competencia abierta que define a la econom\u00eda capitalista. Se trata de entender que no existe una sola actividad productiva, comercial o de servicios que no tenga un competidor aludiendo a su mismo mercado y cuyo inter\u00e9s sea precisamente que su competencia desaparezca.<\/span><\/p>\n<p lang=\"es-CO\"><span style=\"font-family:Arial, sans-serif;\"><!--more-->No es una guerra en sentido figurado. Es una guerra a muerte y una guerra literal. Una guerra que deja muertos en el campo de batalla, expresados en t\u00e9rminos de desempleo, de liquidaci\u00f3n de sociedades, de desaparici\u00f3n de negocios que fueron paradigm\u00e1ticos en el pasado. <\/span><\/p>\n<p lang=\"es-CO\"><span style=\"font-family:Arial, sans-serif;\"><em><strong>La quinta esencia de esta tendencia se centra en el hecho de que sobre cada consumidor confluyen ofertas m\u00faltiples de caracter\u00edsticas virtualmente iguales y que, en consecuencia, la decisi\u00f3n de ese consumidor en beneficio de una u otra alternativa ser\u00e1 siempre en detrimento de las dem\u00e1s.<\/strong><\/em><\/span><\/p>\n<p lang=\"es-CO\"><span style=\"font-family:Arial, sans-serif;\"><strong>2.- El segundo est\u00e1 representado en el creciente poder del consumidor.<\/strong><\/span><\/p>\n<p><span style=\"font-family:Arial, sans-serif;\">El consumidor ya no es el oscuro miembro de una masa inerme y homog\u00e9nea a la que se entregan bienes y servicios para que sean \u201cdevorados\u201d. Se trata de individuos informados, conscientes de sus derechos, reticentes a ser tratados con los m\u00e9todos antiguos de la masificaci\u00f3n; poseedores de un alto concepto de su individualidad, <\/span><span style=\"font-family:Arial, sans-serif;\"><em><strong>con f\u00e9rreos sistemas de creencias que los insertan en micro-culturas propias y excluyentes<\/strong><\/em><\/span><span style=\"font-family:Arial, sans-serif;\"><strong>,<\/strong><\/span><span style=\"font-family:Arial, sans-serif;\"> pero sobre todo, consumidores exigentes y con una total conciencia de su poder real en la econom\u00eda de mercados. <\/span><\/p>\n<p lang=\"es-CO\"><span style=\"font-family:Arial, sans-serif;\"><strong>3.- El tercero es la velocidad del cambio.<\/strong><\/span><\/p>\n<p lang=\"es-CO\"><span style=\"font-family:Arial, sans-serif;\">La tecnolog\u00eda y su din\u00e1mica de desarrollo han logrado imprimir una velocidad nunca antes vista a los procesos de transformaci\u00f3n de la sociedad. Mientras en la d\u00e9cada de los 90s del siglo XX se afirmaba que el conocimiento se duplicaba cada cinco a\u00f1os, ya se prev\u00e9 que el siglo XXI ver\u00e1 como ese conocimiento podr\u00e1 duplicarse en el lapso de unas pocas semanas.<\/span><\/p>\n<p lang=\"es-CO\"><span style=\"font-family:Arial, sans-serif;\">Los cambios ocurren a velocidades impresionantes. Un aparato celular se vuelve obsoleto en el corto lapso de 10 meses, un computador de 18 meses tiene dificultades para correr los nuevos programas que salen al mercado.<\/span><\/p>\n<p lang=\"es-CO\"><span style=\"font-family:Arial, sans-serif;\">Hacer las cosas con los m\u00e9todos del pasado es una apuesta al fracaso. Ma\u00f1ana habr\u00e1 que hacerlas de manera diferente a como las circunstancias lo exigen hoy. Ese es el gran reto.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>guerra de mercados, nuevos consumidores, velocidad del cambio<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[89],"tags":[],"class_list":["post-4405","post","type-post","status-publish","format-standard","hentry","category-comunicacion-inteligente"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/4405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/comments?post=4405"}],"version-history":[{"count":0,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/4405\/revisions"}],"wp:attachment":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/media?parent=4405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/categories?post=4405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/tags?post=4405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}