{"id":4419,"date":"2013-03-05T20:37:30","date_gmt":"2013-03-06T01:37:30","guid":{"rendered":"http:\/\/metalecabeza.org\/?p=1772"},"modified":"2013-03-05T20:37:30","modified_gmt":"2013-03-06T01:37:30","slug":"nuestras-compras-responden-a-nuestros-intereses-yo-costumbres","status":"publish","type":"post","link":"https:\/\/moralescom.com\/site\/nuestras-compras-responden-a-nuestros-intereses-yo-costumbres\/","title":{"rendered":"\u00bfNuestras compras responden a nuestros intereses y\/o costumbres?"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-1774\" style=\"border: 7px solid white; margin: 7px;\" alt=\"ElPrecioNoImporta\" src=\"https:\/\/i0.wp.com\/metalecabeza.moralescom.com\/wp-content\/uploads\/2013\/03\/ElPrecioNoImporta.png?resize=340%2C270\" width=\"340\" height=\"270\" \/>Escribe: Dannisol A.B<\/p>\n<p><strong>\u00bfEl precio no importa?<\/strong><\/p>\n<p style=\"text-align: justify;\">Prexus, en alianza con Market Team, realiz\u00f3 un estudio en 4 ciudades colombianas (Barranquilla, Cali, Bogot\u00e1 y Medell\u00edn) con el fin de definir cuan relevante es el precio en el momento de compra, dicha experiencia mostr\u00f3 que \u201cDe cada cuatro consumidores, uno se comporta como comprador de precio o valor, uno compra por conveniencia y dos compran por relaci\u00f3n\u201d.<\/p>\n<p style=\"text-align: justify;\"><!--more-->Dicho esto, se intuye que los consumidores se fijan poco en el precio y que este, est\u00e1 lejos de determinar su decisi\u00f3n de compra.<\/p>\n<p style=\"text-align: justify;\">De igual forma, se evidenci\u00f3 que un 25% de los encuestados compara precios, el otro 25% compra por cercan\u00eda al punto de venta, y el 50% restante compra la marca de siempre.<\/p>\n<p style=\"text-align: justify;\">Es aqu\u00ed donde los sistemas de creencias afloran, pues subyacen en el cerebro como una orden con direcci\u00f3n y sentido, incuestionable, consolid\u00e1ndose desde la certeza y el inconsciente hasta volver el sentimiento, la percepci\u00f3n y las ideas en verdades absolutas. Por ello, la compra por relaci\u00f3n es la m\u00e1s relevante en los resultados de la encuesta de <a href=\"http:\/\/www.lagrannoticia.com\/economia\/12481-colombianos-compran-por-conveniencia-relacion-precio-y-valor-encuesta-prexus-market-team\" target=\"_blank\" rel=\"noopener\">Prexus<\/a>.<\/p>\n<p style=\"text-align: justify;\">De acuerdo al <a href=\"http:\/\/www.lagrannoticia.com\/files\/PREXUS-MarketTeam_Estudio_Precio_en_Colombia.pdf\" target=\"_blank\" rel=\"noopener\">estudio<\/a>, la compra por relaci\u00f3n consiste en consumir siempre en el mismo lugar y la misma marca. Primero por comodidad, pues el lugar es conocido, y segundo, porque nunca han tenido alg\u00fan inconformismo con\u00a0 el producto.<\/p>\n<p style=\"text-align: justify;\">Por consiguiente, se concluye que la idea de costumbre es definitiva en la elecci\u00f3n de consumo. Se puede pensar que los consumidores se casan con una marca, y no la cambian si como en todo matrimonio, esta no les falla. Es entonces de d\u00f3nde saltan las siguientes inquietudes: \u00bfel consumidor no se cansa de comprar siempre lo mismo?, \u00bfes el consumidor un robot?, \u00bfal consumidor le da pereza cambiar? Pues no. Es tan s\u00f3lo que las decisiones de compra nunca est\u00e1n fuera de los par\u00e1metros socioculturales y pol\u00edticos de las personas \u2013 sujetos de consumo, creencias y relaciones.<\/p>\n<p style=\"text-align: justify;\">La gente no compra s\u00f3lo el producto, compra la marca porque cree en ella y no necesita otra. La marca con su producto cubre cierta necesidad y as\u00ed, el acto de compra no se considera \u201cimpulsivo o al azar\u201d, pues responde a su necesidad y su convicci\u00f3n no consciente de lo que siempre ha cre\u00eddo. En esa medida, los h\u00e1bitos de consumo terminan motivando las compras de una forma programada.<\/p>\n<p style=\"text-align: justify;\">\u00bfY qui\u00e9n altera una programaci\u00f3n, ah?<\/p>\n<p style=\"text-align: justify;\">Entre tanto, \u00bfcu\u00e1l ser\u00eda el papel de las empresas?, \u00bfc\u00f3mo innovar\u00edan en su marca y\/o producto, si la costumbre es tan fuerte en el consumidor y sus posibles prospectos?, \u00bfcu\u00e1l deber\u00eda ser la pol\u00edtica de precios coste o valor de un producto si lo importante se encuentra en su nombre?<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Escribe: Dannisol A.B \u00bfEl precio no importa? Prexus, en alianza con Market Team, realiz\u00f3 un estudio en 4 ciudades colombianas (Barranquilla, Cali, Bogot\u00e1 y Medell\u00edn) con el fin de definir cuan relevante es el precio en el momento de compra, dicha experiencia mostr\u00f3 que \u201cDe cada cuatro consumidores, uno se comporta como comprador de precio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[89],"tags":[227,310,162,94,145],"class_list":["post-4419","post","type-post","status-publish","format-standard","hentry","category-comunicacion-inteligente","tag-compra","tag-compra-por-relacion","tag-consumidores","tag-marca","tag-percepcion"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/4419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/comments?post=4419"}],"version-history":[{"count":0,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/4419\/revisions"}],"wp:attachment":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/media?parent=4419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/categories?post=4419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/tags?post=4419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}