{"id":486,"date":"2010-12-20T18:40:55","date_gmt":"2010-12-20T18:40:55","guid":{"rendered":"http:\/\/metalecabeza.wordpress.com\/?p=486"},"modified":"2010-12-20T18:40:55","modified_gmt":"2010-12-20T18:40:55","slug":"la-neurociencia-y-la-investigacion-publicitaria-2","status":"publish","type":"post","link":"https:\/\/moralescom.com\/site\/la-neurociencia-y-la-investigacion-publicitaria-2\/","title":{"rendered":"La neurociencia y la investigaci\u00f3n publicitaria."},"content":{"rendered":"<p>Un libro del profesor Rodolfo Llin\u00e1s y Patrica Churcland plantea que la actividad mental es actividad cerebral, esto es, que no hay separaci\u00f3n radical entre lo mental y lo neural. La mente y el cerebro no est\u00e1n separados. Se trata de un concepto revolucionario que tiene grandes implicaciones desde el punto de vista de la teor\u00eda del comportamiento. La investigaci\u00f3n tradicional de las percepciones tiene que sufrir un revolc\u00f3n en esta nueva perspectiva. La pregunta es: \u00bfCu\u00e1l ser\u00e1 la orientaci\u00f3n de ese revolc\u00f3n?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un libro del profesor Rodolfo Llin\u00e1s y Patrica Churcland plantea que la actividad mental es actividad cerebral, esto es, que no hay separaci\u00f3n radical entre lo mental y lo neural. La mente y el cerebro no est\u00e1n separados. Se trata de un concepto revolucionario que tiene grandes implicaciones desde el punto de vista de la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[89],"tags":[99],"class_list":["post-486","post","type-post","status-publish","format-standard","hentry","category-comunicacion-inteligente","tag-publicidad"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/comments?post=486"}],"version-history":[{"count":0,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/486\/revisions"}],"wp:attachment":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/media?parent=486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/categories?post=486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/tags?post=486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}