{"id":505,"date":"2011-01-03T15:58:33","date_gmt":"2011-01-03T15:58:33","guid":{"rendered":"http:\/\/metalecabeza.wordpress.com\/?p=505"},"modified":"2011-01-03T15:58:33","modified_gmt":"2011-01-03T15:58:33","slug":"el-imperativo-de-que-la-publicidad-se-re-piense","status":"publish","type":"post","link":"https:\/\/moralescom.com\/site\/el-imperativo-de-que-la-publicidad-se-re-piense\/","title":{"rendered":"El imperativo de que la publicidad se re-piense."},"content":{"rendered":"<p>Ya he dicho en oportunidades anteriores que me impresiona esa especie de estancamiento en el que est\u00e1 sumida la t\u00e9cnica publicitaria. He dicho que me parece simplemente deprimente el hecho de que publicistas y hombres de marketing contin\u00faen aferrados al &#8220;posicionamiento&#8221;, una escuela que tiene ya\u00a0m\u00e1s de cincuenta a\u00f1os de haberse concebido.<\/p>\n<p>El cliente es en el mundo contempor\u00e1neo una persona substancialmente diferente a la que era en las d\u00e9cadas del 70 y el 80 del siglo pasado.<\/p>\n<p>Hoy, cuando disciplinas como la psicolog\u00eda, la etnograf\u00eda, la sociolog\u00eda, la semi\u00f3tica, han avanzado de manera tan dram\u00e1tica, es hora ya de que los publicistas y los hombres de marketing tomen la iniciativa de\u00a0reflexionar sobre la manera como estas disciplinas enriquecen el pensamiento publicitario.<\/p>\n<p>Creo que el problema estriba en el impacto del universo liviano en el oficio publicitario. Los estragos de la cultura light han sembrado una tal incapacidad de reflexi\u00f3n en la publicidad, que pareciera que a los del oficio ya no se les ocurre nada.<\/p>\n<p>Me parece que hay que iniciar una cruzada por recobrar el ejercicio del pensamiento cr\u00edtico en la actividad publicitaria.,.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publicidad, marketing, crisis, light, posicionamiento<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[89],"tags":[],"class_list":["post-505","post","type-post","status-publish","format-standard","hentry","category-comunicacion-inteligente"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/comments?post=505"}],"version-history":[{"count":0,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/505\/revisions"}],"wp:attachment":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/media?parent=505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/categories?post=505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/tags?post=505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}