{"id":966,"date":"2012-04-04T17:02:32","date_gmt":"2012-04-04T17:02:32","guid":{"rendered":"http:\/\/metalecabeza.moralescom.com\/?p=966"},"modified":"2012-04-04T17:02:32","modified_gmt":"2012-04-04T17:02:32","slug":"es-sopechoso-ese-silencio-mudo-de-la-publicidad-y-el-mercadeo-frente-al-dia-del-consumidor","status":"publish","type":"post","link":"https:\/\/moralescom.com\/site\/es-sopechoso-ese-silencio-mudo-de-la-publicidad-y-el-mercadeo-frente-al-dia-del-consumidor\/","title":{"rendered":"Es sospechoso ese silencio mudo de la Publicidad y el Mercadeo frente al d\u00eda del consumidor."},"content":{"rendered":"<p>Escribe:\u00a0Alberto Morales<\/p>\n<p><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-967\" title=\"postsilenciomudodelapublicidadyelmercadeo\" src=\"https:\/\/i0.wp.com\/metalecabeza.moralescom.com\/wp-content\/uploads\/2012\/04\/postsilenciomudodelapublicidadyelmercadeo.jpg?resize=600%2C260\" alt=\"\" width=\"600\" height=\"260\" \/><\/p>\n<p style=\"text-align: justify;\">Si, el pasado 15 de Marzo se celebr\u00f3 el d\u00eda Internacional de los Derechos del Consumidor y salvo el registro noticioso y las menciones al Estatuto del Consumidor que fu\u00e9 sancionado por la Presidencia de la Rep\u00fablica, no hubo pronunciamientos adicionales de ning\u00fan sector de la econom\u00eda.<\/p>\n<p style=\"text-align: justify;\">\u00a0Preocupa que la Publicidad y el Mercadeo tambi\u00e9n estuvieran en silencio, pues en su caso en particular se trata de un acto supremo de inconsecuencia.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">\u00a0Para nadie es un secreto que el mundo de los negocios de hoy est\u00e1 signado por dos tendencias relevantes:<\/p>\n<p style=\"text-align: justify;\">\u00a0<strong>La primera es la que se ha denominado \u201cescenario de guerra\u201d.<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0Y no se trata de darle una nueva denominaci\u00f3n a la \u201ceconom\u00eda de mercado\u201d y al concepto de la \u201clibre concurrencia\u201d.<\/p>\n<p style=\"text-align: justify;\">\u00a0No se trata solamente de reivindicar la condici\u00f3n de competencia abierta que define a la econom\u00eda capitalista. Se trata de entender que no existe una sola actividad productiva, comercial o de servicios que no tenga un competidor aludiendo a su mismo mercado y cuyo inter\u00e9s sea precisamente que su competencia desaparezca.<\/p>\n<p style=\"text-align: justify;\">\u00a0No es una guerra en sentido figurado. Es una guerra a muerte y una guerra literal. Una guerra que deja muertos en el campo de batalla, expresados en t\u00e9rminos de desempleo, de liquidaci\u00f3n de sociedades, de desaparici\u00f3n de negocios que fueron paradigm\u00e1ticos en el pasado.<\/p>\n<p style=\"text-align: justify;\"><strong><em>\u00a0La quinta esencia de esta tendencia\u00a0 se centra en el hecho de que sobre cada consumidor confluyen ofertas m\u00faltiples de caracter\u00edsticas virtualmente iguales y que, en consecuencia, la decisi\u00f3n de ese\u00a0 consumidor en beneficio de\u00a0 una u otra alternativa ser\u00e1 siempre en detrimento de las dem\u00e1s.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0Eso explica que la segunda tendencia sea<\/p>\n<p style=\"text-align: justify;\">\u00a0<strong>El creciente poder del consumidor.<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0El consumidor ya no es el oscuro miembro de una masa inerme y homog\u00e9nea a la que se entregan bienes y servicios para que sean \u201cdevorados\u201d. Se trata de individuos informados, conscientes de sus derechos, reticentes a ser tratados con los m\u00e9todos antiguos de la masificaci\u00f3n; poseedores de un alto concepto de su individualidad, <strong><em>con f\u00e9rreos sistemas de creencias que los insertan en micro-culturas propias y excluyentes<\/em><\/strong>, pero sobre todo, consumidores exigentes y con una total conciencia de su poder real en la econom\u00eda de mercados.<\/p>\n<p style=\"text-align: justify;\">\u00a0Todos los profesionales de la Publicidad y el Mercadeo asumen esas premisas a la manera de axiomas, pero nada de eso aflora en el d\u00eda del consumidor.<\/p>\n<p style=\"text-align: justify;\">\u00a0Es extra\u00f1o.<\/p>\n<p style=\"text-align: justify;\">\u00a0Salvo que los unos y los otros est\u00e9n aterrorizados con las consecuencias que para sus oficios tendr\u00e1 el Estatuto referido y sobre todo en el articulado pertinente a la Publicidad enga\u00f1osa.<\/p>\n<p style=\"text-align: justify;\">\u00a0Puede ser un prejuicio, claro, pero ser\u00eda bueno escuchar una explicaci\u00f3n&#8230;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escribe:\u00a0Alberto Morales Si, el pasado 15 de Marzo se celebr\u00f3 el d\u00eda Internacional de los Derechos del Consumidor y salvo el registro noticioso y las menciones al Estatuto del Consumidor que fu\u00e9 sancionado por la Presidencia de la Rep\u00fablica, no hubo pronunciamientos adicionales de ning\u00fan sector de la econom\u00eda. \u00a0Preocupa que la Publicidad y el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[88,89,92],"tags":[168,109,106,90,143,178,179,96,99],"class_list":["post-966","post","type-post","status-publish","format-standard","hentry","category-comunicacion-perceptual-2","category-comunicacion-inteligente","category-cultumidor","tag-alberto-morales","tag-colombia","tag-comunicacion-perceptual","tag-consumidor","tag-cultumidor-2","tag-derechos-del-consumidor","tag-estatutos-del-consumidor","tag-mercadeo","tag-publicidad"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/comments?post=966"}],"version-history":[{"count":0,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/posts\/966\/revisions"}],"wp:attachment":[{"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/media?parent=966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/categories?post=966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moralescom.com\/site\/wp-json\/wp\/v2\/tags?post=966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}